{"id":10125,"date":"2020-01-20T00:00:00","date_gmt":"2020-01-19T23:00:00","guid":{"rendered":"https:\/\/www.co-nect.fr\/?post_type=product&#038;p=10125"},"modified":"2023-12-06T15:10:37","modified_gmt":"2023-12-06T14:10:37","slug":"miura-bar-stool","status":"publish","type":"product","link":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/","title":{"rendered":"Black Miura Bar Stool"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<ul>\r\n \t<li>Dimensions (W\/D\/H\/H) : 47 x 40 x 81 x 78<\/li>\r\n \t<li>Colour : Black<\/li>\r\n \t<li>Material : Plastic<\/li>\r\n \t<li>Storage : Stackable<\/li>\r\n \t<li>REF TA23<\/li>\r\n<\/ul>","protected":false},"featured_media":10629,"template":"","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Black Miura Bar Stool","_seopress_titles_desc":"Black Miura Bar Stool rental for your event | CO-NECT","_seopress_robots_index":""},"product_brand":[],"product_cat":[78],"product_tag":[],"class_list":{"0":"post-10125","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chairs-armchairs-stools","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Black Miura Bar Stool<\/title>\n<meta name=\"description\" content=\"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Miura Bar Stool\" \/>\n<meta property=\"og:description\" content=\"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect\" \/>\n<meta property=\"og:url\" content=\"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/\" \/>\n<meta property=\"og:site_name\" content=\"Co-nect\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T14:10:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.co-nect.fr\/wp-content\/uploads\/2022\/04\/ta-23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/\",\"url\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/\",\"name\":\"Black Miura Bar Stool\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/co-nect.definima.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ta-23.jpg\",\"datePublished\":\"2020-01-19T23:00:00+00:00\",\"dateModified\":\"2023-12-06T14:10:37+00:00\",\"description\":\"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/#primaryimage\",\"url\":\"https:\\\/\\\/co-nect.definima.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ta-23.jpg\",\"contentUrl\":\"https:\\\/\\\/co-nect.definima.net\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/ta-23.jpg\",\"width\":512,\"height\":512,\"caption\":\"ta23-black-muira-bar-stool\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/catalogue-mobilier\\\/chairs-armchairs-stools\\\/miura-bar-stool\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/co-nect.definima.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Furniture catalog\",\"item\":\"https:\\\/\\\/co-nect.definima.net\\\/catalogue-mobilier\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Black Miura Bar Stool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#website\",\"url\":\"https:\\\/\\\/co-nect.definima.net\\\/\",\"name\":\"Co-nect\",\"description\":\"Ma\u00eetre en \u00e9v\u00e9nements\",\"publisher\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/co-nect.definima.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#organization\",\"name\":\"Les Ortigues\",\"url\":\"https:\\\/\\\/co-nect.definima.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Les Ortigues\"},\"image\":{\"@id\":\"https:\\\/\\\/co-nect.definima.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black Miura Bar Stool","description":"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/","og_locale":"en_US","og_type":"article","og_title":"Black Miura Bar Stool","og_description":"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect","og_url":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/","og_site_name":"Co-nect","article_modified_time":"2023-12-06T14:10:37+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.co-nect.fr\/wp-content\/uploads\/2022\/04\/ta-23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/","url":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/","name":"Black Miura Bar Stool","isPartOf":{"@id":"https:\/\/co-nect.definima.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/#primaryimage"},"image":{"@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/#primaryimage"},"thumbnailUrl":"https:\/\/co-nect.definima.net\/wp-content\/uploads\/2022\/04\/ta-23.jpg","datePublished":"2020-01-19T23:00:00+00:00","dateModified":"2023-12-06T14:10:37+00:00","description":"Location de Black Miura Bar Stool pour vos \u00e9v\u00e9nements | Co-nect","breadcrumb":{"@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/#primaryimage","url":"https:\/\/co-nect.definima.net\/wp-content\/uploads\/2022\/04\/ta-23.jpg","contentUrl":"https:\/\/co-nect.definima.net\/wp-content\/uploads\/2022\/04\/ta-23.jpg","width":512,"height":512,"caption":"ta23-black-muira-bar-stool"},{"@type":"BreadcrumbList","@id":"https:\/\/co-nect.definima.net\/en\/catalogue-mobilier\/chairs-armchairs-stools\/miura-bar-stool\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/co-nect.definima.net\/en\/"},{"@type":"ListItem","position":2,"name":"Furniture catalog","item":"https:\/\/co-nect.definima.net\/catalogue-mobilier\/"},{"@type":"ListItem","position":3,"name":"Black Miura Bar Stool"}]},{"@type":"WebSite","@id":"https:\/\/co-nect.definima.net\/#website","url":"https:\/\/co-nect.definima.net\/","name":"Co-nect","description":"Ma\u00eetre en \u00e9v\u00e9nements","publisher":{"@id":"https:\/\/co-nect.definima.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/co-nect.definima.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/co-nect.definima.net\/#organization","name":"Les Ortigues","url":"https:\/\/co-nect.definima.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/co-nect.definima.net\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Les Ortigues"},"image":{"@id":"https:\/\/co-nect.definima.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/product\/10125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/media\/10629"}],"wp:attachment":[{"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/media?parent=10125"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/product_brand?post=10125"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/product_cat?post=10125"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/co-nect.definima.net\/en\/wp-json\/wp\/v2\/product_tag?post=10125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}